{"id":133,"date":"2011-03-09T17:13:40","date_gmt":"2011-03-09T16:13:40","guid":{"rendered":"http:\/\/www.casinadirosa.it\/?page_id=133"},"modified":"2013-07-01T10:27:11","modified_gmt":"2013-07-01T08:27:11","slug":"wine-tours-tuscany","status":"publish","type":"page","link":"https:\/\/www.casinadirosa.it\/it\/things-to-do-tuscany\/food-drink-tuscany\/wines-of-tuscany\/wine-tours-tuscany\/","title":{"rendered":"Degustazioni di vino"},"content":{"rendered":"<p><\/p>\n<h2>Visita ad una cantina DOC Montecucco con degustazione di vini<\/h2>\n<p>Casina di Rosa organizza per i suoi ospiti delle escursioni con degustazione di DOC Montecucco. \u00c8 possibile su richiesta organizzare degustazioni e visite anche nella zona di altri vini della zona, quali il <strong>Brunello<\/strong>, il <strong>Monteregio<\/strong> di Massa Marittima e il <strong>Chianti<\/strong>.<\/p>\n<p>Il programma delle visite alle cantine del DOC Montecucco comprende (condizioni metereologiche permettendo):<\/p>\n<ul>\n<li>visita ad un&#8217;azienda vinicola<\/li>\n<li>degustazione di vini<\/li>\n<li>un pasto casereccio<\/li>\n<\/ul>\n<p>Il costo a persona per il tour di un&#8217;intera giornata (10-16.30, 4 cantine con degustazione) \u00e8 di 110 euro comprensivi del pasto (oppure 95 euro senza il pasto). L&#8217;offerta \u00e8 riservata esclusivamente agli ospiti di Casina di Rosa.<\/p>\n<p>Il costo per il tour di mezza giornata (3 ore e mezzo, 2 cantine con degustazione) \u00e8 di 75 euro a testa.<\/p>\n<h2>L&#8217;olio e il vino dell&#8217;Alta Maremma<\/h2>\n<p>\u00c8 possibile combinare le escursioni dedicate all&#8217;olio d&#8217;oliva ed al vino DOC Montecucco. In questo caso il prezzo a persona \u00e8 di 135 euro, comprensivo del pasto (oppure 110 euro senza pasto).<\/p>\n<p>Altre pagine di interesse<\/p>\n<ul>\n<li>L&#8217;olio d&#8217;oliva delle colline dell&#8217;Alta Maremma Toscana<\/li>\n<li>Lezioni di cucina toscana<\/li>\n<li>La lavanda in Toscana<\/li>\n<\/ul>\n<p>Foto banner di <a href=\"http:\/\/www.flickr.com\/photos\/charlesfred\/474279148\/sizes\/m\/in\/photostream\/\">CharlesFred<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Visita ad una cantina DOC Montecucco con degustazione di vini Casina di Rosa organizza per i suoi ospiti delle escursioni con degustazione di DOC Montecucco. \u00c8 possibile su richiesta organizzare degustazioni e visite anche nella zona di altri vini della zona, quali il Brunello, il Monteregio di Massa Marittima e il Chianti. Il programma delle [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":134,"parent":130,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-133","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.casinadirosa.it\/it\/wp-json\/wp\/v2\/pages\/133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casinadirosa.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.casinadirosa.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.casinadirosa.it\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.casinadirosa.it\/it\/wp-json\/wp\/v2\/comments?post=133"}],"version-history":[{"count":8,"href":"https:\/\/www.casinadirosa.it\/it\/wp-json\/wp\/v2\/pages\/133\/revisions"}],"predecessor-version":[{"id":431,"href":"https:\/\/www.casinadirosa.it\/it\/wp-json\/wp\/v2\/pages\/133\/revisions\/431"}],"up":[{"embeddable":true,"href":"https:\/\/www.casinadirosa.it\/it\/wp-json\/wp\/v2\/pages\/130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.casinadirosa.it\/it\/wp-json\/wp\/v2\/media\/134"}],"wp:attachment":[{"href":"https:\/\/www.casinadirosa.it\/it\/wp-json\/wp\/v2\/media?parent=133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}